{"id":45803,"date":"2025-03-06T06:00:00","date_gmt":"2025-03-06T14:00:00","guid":{"rendered":"https:\/\/sentientmedia.org\/que-significa-desierto-alimentario-y-por-que-el-termino-es-enganoso\/"},"modified":"2025-05-08T14:58:44","modified_gmt":"2025-05-08T21:58:44","slug":"que-significa-desierto-alimentario-y-por-que-el-termino-es-enganoso","status":"publish","type":"post","link":"https:\/\/sentientmedia.org\/es\/que-significa-desierto-alimentario-y-por-que-el-termino-es-enganoso\/","title":{"rendered":"Qu\u00e9 significa \u201cdesierto alimentario\u201d y por qu\u00e9 el t\u00e9rmino es enga\u00f1oso"},"content":{"rendered":"\n<p>La administraci\u00f3n Trump est\u00e1 tomando mayor control sobre <a href=\"https:\/\/sentientmedia.org\/food-apartheid-food-desert\/\">qui\u00e9n tiene acceso a los alimentos<\/a> en Estados Unidos. Esto es una mala noticia para quienes luchan por llegar a fin de mes: varios de los nuevos nombramientos del presidente Donald Trump han manifestado su disposici\u00f3n a imponer l\u00edmites a los programas de acceso a alimentos, especialmente al Programa Asistencial de Nutrici\u00f3n Suplementaria (SNAP, por sus siglas en ingl\u00e9s). Si bien los<a href=\"https:\/\/www.americanprogress.org\/article\/how-the-trump-administration-could-leave-families-hungry-potential-cuts-to-snap-in-2025-and-beyond\/\" target=\"_blank\" rel=\"noopener\"> cambios en la pol\u00edtica del SNAP <\/a>afectar\u00edan a millones de personas, el impacto que sufrir\u00edan quienes viven en los llamados \u201cdesiertos alimentarios\u201d podr\u00eda verse agravado por la falta de acceso f\u00e1cil a los alimentos.  <\/p>\n\n<p>La inseguridad alimentaria no es un problema sencillo y gran parte del problema reside en la forma en que nos referimos a ella, incluyendo el t\u00e9rmino \u201cdesierto alimentario\u201d. <a href=\"https:\/\/foodispower.org\/access-health\/food-deserts\/\" target=\"_blank\" rel=\"noopener\">El t\u00e9rmino \u201cdesierto alimentario\u201d<\/a> es un \u201cclaro ejemplo del poder del lenguaje\u201d, seg\u00fan declara a Sentient Erica Zurawski, investigadora especializada en el estudio de los alimentos.<\/p>\n\n<p>En un <a href=\"https:\/\/read.dukeupress.edu\/environmental-humanities\/article\/17\/1\/88\/399035\/Food-Desert-ImperialismThe-Colonial-Legacy-of-the\" target=\"_blank\" rel=\"noopener\">art\u00edculo publicado recientemente<\/a>, Zurawski expone c\u00f3mo el t\u00e9rmino est\u00e1 impregnado de suposiciones racistas sobre el desarrollo, ignora los paisajes alimentarios, a veces diversos, de los \u201cdesiertos alimentarios\u201d y culpa a las mismas personas que sufren inseguridad alimentaria. Las pol\u00edticas que se centran \u00fanicamente en el acceso a los alimentos a menudo no logran sus objetivos; sin embargo, eliminar todos los programas de acceso a los alimentos (como el SNAP) podr\u00eda tener resultados a\u00fan m\u00e1s devastadores. <\/p>\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h2 class=\"wp-block-heading\">La historia del t\u00e9rmino \u201cdesierto alimentario\u201d<\/h2>\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p>Los residentes de viviendas p\u00fablicas en <a href=\"https:\/\/www.cdc.gov\/pcd\/issues\/2009\/jul\/08_0163.htm\" target=\"_blank\" rel=\"noopener\">Escocia acu\u00f1aron originalmente el t\u00e9rmino \u201cdesierto alimentario\u201d <\/a>para describir la experiencia de vivir con acceso limitado a recursos. A partir de ah\u00ed, los cient\u00edficos de datos adoptaron r\u00e1pidamente el t\u00e9rmino, utilizando programas de mapeo para delimitar las \u00e1reas que constitu\u00edan desiertos alimentarios. <\/p>\n\n<p>Sin embargo, al traducir el t\u00e9rmino para que tuviera implicaciones reales en los datos, \u201cdesierto alimentario\u201d pas\u00f3 a significar \u00fanicamente \u00e1reas sin supermercados. Si bien la falta de supermercados en una zona es un problema vinculado a una historia de segregaci\u00f3n racial en Estados Unidos, centrarse \u00fanicamente en este problema <a href=\"https:\/\/sentientmedia.org\/food-apartheid-food-desert\/\">impide un debate m\u00e1s profundo sobre la pobreza y los salarios<\/a>. Si se deja de hablar de pobreza, afirma Zurawski, se tiende a dejar de hablar de salarios, y una vez que esto sucede, \u201cel estatus socioecon\u00f3mico se desvanece y, en su lugar, se obtiene simplemente este terreno geogr\u00e1fico en la distancia a los supermercados\u201d.   <\/p>\n\n<p>Aun as\u00ed, los responsables pol\u00edticos favorecieron la nueva definici\u00f3n de desierto alimentario. Simplific\u00f3 las complejas experiencias de vivir en zonas con menor acceso a alimentos, a la vez que apoyaba la idea de que las acciones basadas en el mercado, como la construcci\u00f3n de m\u00e1s supermercados, podr\u00edan resolver el problema, explica Zurawski. <\/p>\n\n<p>Pol\u00edticos de ambos partidos se han centrado en ocasiones en el acceso directo a los alimentos por encima de estos problemas sist\u00e9micos m\u00e1s profundos y complejos. Zurawski argumenta que algunas de las propuestas de <a href=\"https:\/\/www.newsweek.com\/rfk-jr-school-lunches-michele-obama-2031209\" target=\"_blank\" rel=\"noopener\">Robert F. Kennedy Jr. evocan aspectos de la campa\u00f1a \u201cLet&#8217;s Move\u201d de Michelle Obama<\/a>, con iniciativas como, por ejemplo, llevar barras de ensaladas a las escuelas. Estos programas, y los mensajes que se utilizan para describirlos, se centran principalmente en <a href=\"https:\/\/obamawhitehouse.archives.gov\/blog\/2010\/02\/24\/taking-food-deserts\" target=\"_blank\" rel=\"noopener\">la idea de que los desiertos alimentarios son<\/a>, tanto impl\u00edcita como expl\u00edcitamente, p\u00e1ramos nutricionales, ignorando las causas sociales y pol\u00edticas m\u00e1s amplias de la inseguridad alimentaria. Y, seg\u00fan la investigaci\u00f3n, estos<a href=\"https:\/\/journals.sagepub.com\/doi\/10.1177\/1090198119853009?url_ver=Z39.88-2003&amp;rfr_id=ori:rid:crossref.org&amp;rfr_dat=cr_pub%20%200pubmed\" target=\"_blank\" rel=\"noopener\"> programas, que abordan el problema principalmente desde el aspecto del acceso<\/a>, han resultado ser, en gran medida, <a href=\"https:\/\/www.nyu.edu\/about\/news-publications\/news\/2019\/december\/what-really-happens-when-a-grocery-store-opens-in-a--food-desert.html\" target=\"_blank\" rel=\"noopener\">un fracaso<\/a>.   <\/p>\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h2 class=\"wp-block-heading\">Suposiciones falsas impl\u00edcitas en el t\u00e9rmino \u201cdesierto alimentario\u201d<\/h2>\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p>El t\u00e9rmino \u201cdesierto alimentario\u201d no solo simplifica excesivamente un problema complejo y diversas experiencias vividas, sino que tambi\u00e9n se basa en gran medida en ideas err\u00f3neas sobre los desiertos, <a href=\"https:\/\/read.dukeupress.edu\/environmental-humanities\/article\/17\/1\/88\/399035\/Food-Desert-ImperialismThe-Colonial-Legacy-of-the\" target=\"_blank\" rel=\"noopener\">argumenta Zurawski en su art\u00edculo<\/a>.<\/p>\n\n<p>Contrariamente a la creencia popular, los <a href=\"https:\/\/phys.org\/news\/2023-02-brimming-life-poorly-understood-ecosystems.html\" target=\"_blank\" rel=\"noopener\">desiertos est\u00e1n repletos de vida<\/a>, tanto humana como animal. Bas\u00e1ndonos en nuestras suposiciones sobre los paisajes \u00e1ridos, el t\u00e9rmino \u201cdesierto alimentario\u201d evoca la idea de ausencia de alimentos. Esto no siempre es as\u00ed, escribe Zurawski, quien se\u00f1ala que las fuentes locales de alimentos, como las bodegas, los huertos familiares y las tiendas de barrio, se excluyen de las definiciones de \u201cdesiertos alimentarios\u201d.  <\/p>\n\n<p>Descartar las fuentes de alimentos que no sean las grandes superficies de alimentaci\u00f3n contribuye a la idea de que los desiertos alimentarios necesitan desarrollo para reducir la inseguridad alimentaria. Es una idea estrechamente vinculada a las <a href=\"https:\/\/thereader.mitpress.mit.edu\/dispelling-myths-about-drylands\/\" target=\"_blank\" rel=\"noopener\">perspectivas colonialistas que consideran que los paisajes des\u00e9rticos <\/a>necesitan mejoras mediante el desarrollo para maximizar la rentabilidad. <\/p>\n\n<p>Todas estas ideas tienden a basarse en <a href=\"https:\/\/www.psychologicalscience.org\/observer\/want-healthier-americans-shift-the-focus-from-personal-choice\" target=\"_blank\" rel=\"noopener\">suposiciones racistas hacia los residentes <\/a>de los desiertos alimentarios, consider\u00e1ndolos personalmente responsables de su propia inseguridad alimentaria. Debido a numerosas pol\u00edticas destinadas a aumentar la desigualdad racial, incluyendo la segregaci\u00f3n residencial y otras barreras para la creaci\u00f3n de riqueza generacional que enfrentan las personas negras e ind\u00edgenas estadounidenses, los barrios de mayor\u00eda negra tienen significativamente <a href=\"https:\/\/www.socialpolicylab.org\/post\/grow-your-blog-community#\" target=\"_blank\" rel=\"noopener\">menos probabilidades de tener un supermercado <\/a>que los barrios de mayor\u00eda blanca. <\/p>\n\n<p>A pesar de las pol\u00edticas racialmente discriminatorias que han contribuido a las disparidades raciales en la ubicaci\u00f3n de los supermercados, en t\u00e9rminos absolutos, las personas blancas son <a href=\"https:\/\/frac.org\/blog\/new-usda-report-provides-picture-of-who-participates-in-snap\" target=\"_blank\" rel=\"noopener\">el grupo demogr\u00e1fico que m\u00e1s accede a los beneficios del SNAP<\/a>. Sin embargo, en comparaci\u00f3n con <a href=\"https:\/\/www.neilsberg.com\/insights\/united-states-population-by-race\/\" target=\"_blank\" rel=\"noopener\">la demograf\u00eda general de Estados Unidos<\/a>, las comunidades hist\u00f3ricamente marginadas acceden al programa de forma desproporcionada. <\/p>\n\n<p>Aunque existen numerosas cr\u00edticas al <a href=\"https:\/\/sentientmedia.org\/snap\/\">SNAP, el programa ayuda a proporcionar alimentos<\/a> a familias que padecen hambre e inseguridad alimentaria. Sin embargo, bajo la administraci\u00f3n Trump, el programa podr\u00eda enfrentar cambios significativos, lo que comprometer\u00eda a\u00fan m\u00e1s el acceso a los alimentos en varias comunidades. <\/p>\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h2 class=\"wp-block-heading\">\u00bfQu\u00e9 podr\u00edan significar los cambios de pol\u00edtica para los beneficiarios del SNAP?<\/h2>\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p>Los beneficios del SNAP se describen en la Ley Agr\u00edcola, un proyecto de ley t\u00edpicamente bipartidista que establece las normas para numerosos programas, incluyendo muchos relacionados con la seguridad alimentaria \u2014como el SNAP\u2014, as\u00ed como subsidios agr\u00edcolas, seguros de cosechas y desarrollo rural. Normalmente, la legislaci\u00f3n se renueva cada cinco a\u00f1os, un proceso que <a href=\"https:\/\/sentientmedia.org\/trump-harris-win-farm-bill\/\">deb\u00eda tener lugar en 2023, pero que se estanc\u00f3<\/a> en el Congreso. <\/p>\n\n<p>Un posible presupuesto que se est\u00e1 considerando actualmente en el Congreso, controlado por los republicanos, requerir\u00eda que el Comit\u00e9 de Agricultura <a href=\"https:\/\/www.cbpp.org\/research\/food-assistance\/millions-of-low-income-households-would-lose-food-aid-under-proposed-house\" target=\"_blank\" rel=\"noopener\">recortara el presupuesto de sus programas<\/a> en unos 230.000 millones de d\u00f3lares en 10 a\u00f1os. Estos recortes casi con seguridad requerir\u00edan cambios en el SNAP, ya sea restringiendo la elegibilidad o reduciendo los beneficios. La C\u00e1mara de Representantes aprob\u00f3 la resoluci\u00f3n presupuestaria el 25 de febrero.  <\/p>\n\n<p>Mientras tanto, el Congreso tambi\u00e9n est\u00e1 considerando <a href=\"https:\/\/www.cbpp.org\/press\/statements\/house-republican-budget-would-mean-higher-costs-less-help-for-families-more-tax\" target=\"_blank\" rel=\"noopener\">extender los recortes de impuestos que disfrutaron los estadounidenses m\u00e1s ricos<\/a>, implementados durante la \u00faltima administraci\u00f3n Trump. Hacerlo requerir\u00eda un recorte dr\u00e1stico del gasto de unos 1,5 billones de d\u00f3lares, seg\u00fan el Centro de Prioridades Presupuestarias y Pol\u00edticas. <\/p>\n\n<p>Los programas de nutrici\u00f3n, como el SNAP, representan el 76 % de la <a href=\"https:\/\/www.ers.usda.gov\/topics\/farm-bill\/2018-farm-bill#\" target=\"_blank\" rel=\"noopener\">financiaci\u00f3n de la Ley Agr\u00edcola de 2018<\/a>. En 2023, los beneficios del SNAP facilitaron el <a href=\"https:\/\/www.ers.usda.gov\/data-products\/chart-gallery\/chart-detail?chartId=55416#\" target=\"_blank\" rel=\"noopener\">acceso a alimentos a 42,1 millones de personas<\/a>. Ahora, con un nuevo liderazgo tanto en el Departamento de Agricultura (USDA) como en el Departamento de Salud y Servicios Humanos, y con la renovaci\u00f3n de la Ley Agr\u00edcola pendiente, el futuro de los programas de asistencia alimentaria sigue siendo incierto. Lo que s\u00ed es evidente es que algunas personas corren mayor riesgo que otras debido a los cambios en la pol\u00edtica del SNAP.   <\/p>\n\n<p>A finales de febrero, <a href=\"https:\/\/sentientmedia.org\/brooke-rollins-trumps-agricultural-secretary-pick\/\">la secretaria del USDA, Brooke Rollins<\/a>, emiti\u00f3 una directiva destinada a impedir que los inmigrantes indocumentados accedan a los pagos del SNAP. Si bien, seg\u00fan el sitio web del USDA, \u201clos no ciudadanos indocumentados no son ni nunca <a href=\"https:\/\/www.fns.usda.gov\/snap\/recipient\/eligibility\/non-citizen\" target=\"_blank\" rel=\"noopener\">han sido elegibles para el SNAP<\/a>\u201c, la directiva inclu\u00eda pocos detalles precisos que permitieran saber con certeza c\u00f3mo se promulgar\u00eda. <\/p>\n\n<p>Robert F. Kennedy Jr. tambi\u00e9n desempe\u00f1ar\u00e1 un papel importante, ya que el controvertido secretario construy\u00f3 su movimiento \u201cMake America Healthy Again\u201d (\u201cHagamos que Estados Unidos vuelva a ser saludable\u201d) a partir de sus<a href=\"https:\/\/sentientmedia.org\/rfk-jr-anti-processed-plant-based-foods\/\"> cr\u00edticas a los alimentos procesados<\/a>. Como resultado, durante sus audiencias de confirmaci\u00f3n y en entrevistas con los medios desde entonces, ha manifestado su apoyo a las pol\u00edticas que limitan la cantidad de <a href=\"https:\/\/sentientmedia.org\/rfk-jr-anti-processed-plant-based-foods\/\">alimentos que se pueden comprar con los beneficios del SNAP.<\/a> <\/p>\n\n<p>\u201cMe temo que los recortes al SNAP que propone el Partido Republicano en la C\u00e1mara de Representantes, sumado a la propuesta de RFK Jr. de eliminar los alimentos procesados \u200b\u200by ultraprocesados \u200b\u200bde los beneficios del SNAP, realmente no ofrecen ninguna protecci\u00f3n para quienes solo necesitan comida\u201d, afirma Zurawski.<\/p>\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h2 class=\"wp-block-heading\">En conclusi\u00f3n<\/h2>\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p>En definitiva, el acceso a los alimentos no es un problema que pueda aislarse y abordarse de forma separada, sino que requiere reconocer la interconexi\u00f3n de la gama de cuestiones que conforman el sistema alimentario. \u201cLos problemas sociales est\u00e1n profundamente entrelazados en una especie de red\u201d, afirma Zurawski. \u201cHablar de agricultura, de trabajo, de bienestar social, de medioambiente y cambio clim\u00e1tico es tambi\u00e9n hablar de alimentaci\u00f3n\u201d.  <\/p>\n\n<p>Zurawski duda de la eficacia de abordar la inseguridad alimentaria mediante la formulaci\u00f3n de pol\u00edticas, especialmente en el clima pol\u00edtico actual. En cambio, busca soluciones comunitarias, como las iniciativas de ayuda mutua, para contrarrestar las pol\u00edticas cada vez m\u00e1s deficientes destinadas a abordar la inseguridad alimentaria. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una nueva investigaci\u00f3n describe los supuestos anti-negros y anti-ind\u00edgenas del t\u00e9rmino.<\/p>\n","protected":false},"author":324,"featured_media":44731,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"apple_news_api_created_at":"","apple_news_api_id":"","apple_news_api_modified_at":"","apple_news_api_revision":"","apple_news_api_share_url":"","apple_news_cover_media_provider":"image","apple_news_coverimage":0,"apple_news_coverimage_caption":"","apple_news_cover_video_id":0,"apple_news_cover_video_url":"","apple_news_cover_embedwebvideo_url":"","apple_news_is_hidden":"","apple_news_is_paid":"","apple_news_is_preview":"","apple_news_is_sponsored":"","apple_news_maturity_rating":"","apple_news_metadata":"\"\"","apple_news_pullquote":"","apple_news_pullquote_position":"","apple_news_slug":"","apple_news_sections":[],"apple_news_suppress_video_url":false,"apple_news_use_image_component":false,"footnotes":""},"categories":[2174,2173],"tags":[2771,2162,2395,2770],"sm-feature":[2861],"coauthors":[2380],"class_list":["post-45803","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nutricion","category-salud","tag-desiertos-alimentarios","tag-explicativo","tag-nutricion","tag-salud-publica","sm-feature-explicativo"],"acf":[],"apple_news_notices":[],"_links":{"self":[{"href":"https:\/\/sentientmedia.org\/es\/wp-json\/wp\/v2\/posts\/45803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sentientmedia.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sentientmedia.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sentientmedia.org\/es\/wp-json\/wp\/v2\/users\/324"}],"replies":[{"embeddable":true,"href":"https:\/\/sentientmedia.org\/es\/wp-json\/wp\/v2\/comments?post=45803"}],"version-history":[{"count":1,"href":"https:\/\/sentientmedia.org\/es\/wp-json\/wp\/v2\/posts\/45803\/revisions"}],"predecessor-version":[{"id":45804,"href":"https:\/\/sentientmedia.org\/es\/wp-json\/wp\/v2\/posts\/45803\/revisions\/45804"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sentientmedia.org\/es\/wp-json\/wp\/v2\/media\/44731"}],"wp:attachment":[{"href":"https:\/\/sentientmedia.org\/es\/wp-json\/wp\/v2\/media?parent=45803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sentientmedia.org\/es\/wp-json\/wp\/v2\/categories?post=45803"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sentientmedia.org\/es\/wp-json\/wp\/v2\/tags?post=45803"},{"taxonomy":"sm-feature","embeddable":true,"href":"https:\/\/sentientmedia.org\/es\/wp-json\/wp\/v2\/sm-feature?post=45803"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/sentientmedia.org\/es\/wp-json\/wp\/v2\/coauthors?post=45803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}