{"id":50152,"date":"2025-12-02T08:00:00","date_gmt":"2025-12-02T16:00:00","guid":{"rendered":"https:\/\/sentientmedia.org\/estudio-sugiere-que-casi-todo-el-mundo-tendra-que-cambiar-su-dieta-de-aqui-a-2050-para-cumplir-los-objetivos-climaticos\/"},"modified":"2026-01-15T10:55:41","modified_gmt":"2026-01-15T18:55:41","slug":"estudio-sugiere-que-casi-todo-el-mundo-tendra-que-cambiar-su-dieta-de-aqui-a-2050-para-cumplir-los-objetivos-climaticos","status":"publish","type":"post","link":"https:\/\/sentientmedia.org\/es\/estudio-sugiere-que-casi-todo-el-mundo-tendra-que-cambiar-su-dieta-de-aqui-a-2050-para-cumplir-los-objetivos-climaticos\/","title":{"rendered":"Estudio sugiere que casi todo el mundo tendr\u00e1 que cambiar su dieta de aqu\u00ed a 2050 para cumplir los objetivos clim\u00e1ticos"},"content":{"rendered":"\n<p>Casi todas las personas del planeta tendr\u00e1n que cambiar su forma de alimentarse de aqu\u00ed a 2050 para ayudar a frenar los efectos del cambio clim\u00e1tico y, para una parte considerable de la poblaci\u00f3n, ese cambio debe comenzar de inmediato. Utilizando datos de 2012, un nuevo estudio concluye que 2,700 millones de personas est\u00e1n generando contaminaci\u00f3n clim\u00e1tica por encima de los l\u00edmites establecidos en la <a href=\"https:\/\/unfccc.int\/process-and-meetings\/the-paris-agreement\" target=\"_blank\" rel=\"noopener\">Convenci\u00f3n Clim\u00e1tica de Par\u00eds<\/a>. Estas cifras en aumento est\u00e1n impulsadas en gran medida por el consumo de carne en todo el mundo, y <a href=\"https:\/\/ourworldindata.org\/meat-production\" target=\"_blank\" rel=\"noopener\">la demanda sigue creciendo<\/a>.  <\/p>\n\n<p>Publicado este mes en Environmental Research: Food Systems por investigadores de la Universidad de Columbia Brit\u00e1nica, el <a href=\"https:\/\/iopscience.iop.org\/article\/10.1088\/2976-601X\/ae10c0\/pdf\" target=\"_blank\" rel=\"noopener\">estudio<\/a> estima que el 44 % de la poblaci\u00f3n mundial en 2012 segu\u00eda dietas que produc\u00edan emisiones de gases de efecto invernadero demasiado elevadas para mantenerse por debajo del umbral m\u00e1ximo de 2 \u00b0C de calentamiento establecido en el Acuerdo de Par\u00eds.<\/p>\n\n<p>Cuando se tiene en cuenta el<a href=\"https:\/\/www.un.org\/en\/desa\/world-population-projected-reach-98-billion-2050-and-112-billion-2100\" target=\"_blank\" rel=\"noopener\"> crecimiento poblacional<\/a>, las cifras empeoran. La investigaci\u00f3n estima que el 91 % de esa misma poblaci\u00f3n va camino de sobrepasar los objetivos clim\u00e1ticos de Par\u00eds de aqu\u00ed a 2050. <\/p>\n\n<p>\u201cLo que eso significa es que m\u00e1s personas est\u00e1n implicadas en la reducci\u00f3n de las emisiones relacionadas con los sistemas alimentarios\u201d, afirma Navin Ramankutty, investigador de sistemas alimentarios globales en la Universidad de Columbia Brit\u00e1nica y uno de los autores del estudio, a Sentient. Seg\u00fan los investigadores, al menos el 40 % de la poblaci\u00f3n mundial en 2012 superaba el umbral de emisiones per c\u00e1pita y, si el mundo espera cumplir los objetivos clim\u00e1ticos establecidos en ese entonces, necesita cambiar su dieta ahora mismo, en particular <a href=\"https:\/\/sentientmedia.org\/es\/por-que-comer-carne-es-malo-para-el-medioambiente-y-el-cambio-climatico\/\">reduciendo el consumo de carne, especialmente de res<\/a>, y de otros alimentos de origen animal. <\/p>\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h2 class=\"wp-block-heading\">\u00bfQui\u00e9n se est\u00e1 comiendo el planeta?<\/h2>\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p>El sistema alimentario representa aproximadamente<a href=\"https:\/\/www.nature.com\/articles\/s43016-021-00225-9\" target=\"_blank\" rel=\"noopener\"> un tercio de las emisiones globales de gases de efecto invernadero<\/a>. Entre los factores que impulsan las emisiones relacionadas con los alimentos se incluyen el metano de los eructos del ganado, el \u00f3xido nitroso del uso de fertilizantes y la deforestaci\u00f3n. <\/p>\n\n<p>La investigaci\u00f3n de la Universidad de Columbia Brit\u00e1nica dividi\u00f3 a la poblaci\u00f3n de cada pa\u00eds en 10 grupos de ingresos para estimar su consumo de alimentos. Las emisiones, descubrieron, tienden a estar vinculadas a varios factores, entre ellos el nivel de ingresos de una persona, sus preferencias alimentarias y el acceso desigual a los alimentos, entre otros. <\/p>\n\n<p>El 15 % superior de los emisores es responsable del 30 % de todas las emisiones relacionadas con la dieta, la misma proporci\u00f3n que la mitad inferior de la poblaci\u00f3n mundial, seg\u00fan el estudio. Los mayores contribuyentes no siempre son las personas m\u00e1s ricas del mundo, sino a menudo las m\u00e1s adineradas dentro de pa\u00edses con altas emisiones, en muchos casos debido a dietas ricas en carne de res y otros alimentos de origen animal. <\/p>\n\n<p>Dos quintas partes del 10 % superior de emisores del mundo viven en Am\u00e9rica del Sur, donde la mayor parte del ganado se cr\u00eda en sistemas extensivos de pastoreo. Estos sistemas tienden a generar m\u00e1s emisiones que la carne de res procedente de corrales de engorde, se\u00f1ala el estudio. El <a href=\"https:\/\/sentientmedia.org\/es\/por-que-comer-carne-es-malo-para-el-medioambiente-y-el-cambio-climatico\/\">uso de la tierra y la deforestaci\u00f3n<\/a> conllevan a un elevado coste en emisiones clim\u00e1ticas. <\/p>\n\n<p>El 23 % del 10 % superior de emisores procede de Estados Unidos, que consume <a href=\"https:\/\/sentientmedia.org\/beef-consumption-in-the-us\/\">m\u00e1s que cualquier otro pa\u00eds<\/a>.<\/p>\n\n<p>La Rep\u00fablica Centroafricana fue un caso at\u00edpico sorprendente. A pesar de la pobreza generalizada, el 10 % m\u00e1s rico del pa\u00eds presenta algunas de las emisiones diet\u00e9ticas m\u00e1s altas del mundo, impulsadas por varios factores, entre ellos una riqueza altamente concentrada que permite a un peque\u00f1o grupo de personas consumir grandes cantidades de alimentos con altas emisiones. <\/p>\n\n<p>El estudio se basa en datos que excluyen los alimentos procedentes de la agricultura de subsistencia, huertos o fuentes silvestres, lo que significa que las dietas y las emisiones de las poblaciones m\u00e1s pobres podr\u00edan estar subestimadas. Otra limitaci\u00f3n del estudio, explica Juan Diego Martinez, coautor del trabajo, a Sentient, es que asume que las personas m\u00e1s ricas consumen m\u00e1s carne, pero existen personas con altos ingresos que optan por dietas vegetarianas o veganas. <\/p>\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h2 class=\"wp-block-heading\">Dietas que reducen emisiones y nutren a las personas<\/h2>\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p>La alimentaci\u00f3n es uno de los principales contribuyentes al calentamiento del planeta y una necesidad humana esencial, lo que plantea un desaf\u00edo complejo: c\u00f3mo reducir las emisiones sin comprometer el acceso a la nutrici\u00f3n. En 2023, 733 millones de personas, aproximadamente <a href=\"https:\/\/www.who.int\/news\/item\/24-07-2024-hunger-numbers-stubbornly-high-for-three-consecutive-years-as-global-crises-deepen--un-report\" target=\"_blank\" rel=\"noopener\">una de cada 11, padecieron hambre en todo el mundo<\/a>. Quienes tienen menos acceso a los alimentos son quienes menos contribuyen a la contaminaci\u00f3n clim\u00e1tica.  <\/p>\n\n<p>El nuevo estudio estima que bastar\u00eda con que el 0.4 % de la poblaci\u00f3n mundial en 2012 redujera sus emisiones para dejar espacio a que el 9 % pudiera adoptar dietas m\u00e1s adecuadas desde el punto de vista nutricional. \u201cSi aumentamos el consumo de las personas que ya siguen dietas de muy bajo impacto, eso realmente no marca una gran diferencia\u201d, afirma Martinez. <\/p>\n\n<p>Es posible reducir las emisiones relacionadas con los alimentos sin sacrificar la salud. Adoptar una \u201cdieta de salud planetaria\u201d, rica en frutas, verduras, frutos secos, legumbres y cereales integrales, con cantidades moderadas de carne y l\u00e1cteos, podr\u00eda reducir a la mitad las emisiones asociadas a la alimentaci\u00f3n y, al mismo tiempo, alimentar a <a href=\"https:\/\/eatforum.org\/update\/eat-lancet-commission-warns-food-systems-breach-planetary-limits\/\" target=\"_blank\" rel=\"noopener\">9,600 millones de personas en 2050<\/a>, seg\u00fan sugieren las investigaciones. <\/p>\n\n<p>Las alternativas vegetales y otras alternativas a la carne pueden desempe\u00f1ar un papel en la sustituci\u00f3n de la carne, seg\u00fan indican otros estudios. Un art\u00edculo publicado por investigadores de la Universidad de California en Santa Cruz y la consultora Accenture sugiri\u00f3 que el 60 % de los alimentos de origen animal tendr\u00eda que ser <a href=\"https:\/\/sentientmedia.org\/alternative-proteins-best-bet-to-curb-food-emissions\/\">reemplazado por alternativas vegetales o cultivadas<\/a> de aqu\u00ed a 2050 para mantener el sistema alimentario dentro de los l\u00edmites clim\u00e1ticos. Los retrasos, advirtieron los autores, exigir\u00edan una transformaci\u00f3n a\u00fan m\u00e1s dr\u00e1stica de las dietas globales. Sea cual sea el sustituto, los autores recomiendan <a href=\"https:\/\/sentientmedia.org\/es\/quieres-reducir-el-consumo-de-carne-estudios-sugieren-que-un-enfoque-flexible-tiene-mas-poder-de-permanencia\/\">reducir el consumo de carne y l\u00e1cteos<\/a>. Mart\u00ednez dice que para quienes consideran que hacerse veganos o vegetarianos es \u201cun no rotundo\u201d, la carne de res puede ser un buen punto de partida para reducir el consumo. \u201cSi hay un compromiso que hacer\u201d, afirma, \u201ces reducir primero el consumo de carne de res\u201d.     <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los investigadores estiman que el 44 % de la poblaci\u00f3n en 2012 ten\u00eda h\u00e1bitos alimentarios que impulsaban las emisiones relacionadas con los alimentos.<\/p>\n","protected":false},"author":533,"featured_media":49630,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"apple_news_api_created_at":"","apple_news_api_id":"","apple_news_api_modified_at":"","apple_news_api_revision":"","apple_news_api_share_url":"","apple_news_cover_media_provider":"image","apple_news_coverimage":0,"apple_news_coverimage_caption":"","apple_news_cover_video_id":0,"apple_news_cover_video_url":"","apple_news_cover_embedwebvideo_url":"","apple_news_is_hidden":"","apple_news_is_paid":"","apple_news_is_preview":"","apple_news_is_sponsored":"","apple_news_maturity_rating":"","apple_news_metadata":"\"\"","apple_news_pullquote":"","apple_news_pullquote_position":"","apple_news_slug":"","apple_news_sections":[],"apple_news_suppress_video_url":false,"apple_news_use_image_component":false,"footnotes":""},"categories":[2211,2234],"tags":[],"sm-feature":[2867],"coauthors":[2825],"class_list":["post-50152","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia","category-investigacion-es-2","sm-feature-noticias"],"acf":[],"apple_news_notices":[],"_links":{"self":[{"href":"https:\/\/sentientmedia.org\/es\/wp-json\/wp\/v2\/posts\/50152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sentientmedia.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sentientmedia.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sentientmedia.org\/es\/wp-json\/wp\/v2\/users\/533"}],"replies":[{"embeddable":true,"href":"https:\/\/sentientmedia.org\/es\/wp-json\/wp\/v2\/comments?post=50152"}],"version-history":[{"count":1,"href":"https:\/\/sentientmedia.org\/es\/wp-json\/wp\/v2\/posts\/50152\/revisions"}],"predecessor-version":[{"id":50153,"href":"https:\/\/sentientmedia.org\/es\/wp-json\/wp\/v2\/posts\/50152\/revisions\/50153"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sentientmedia.org\/es\/wp-json\/wp\/v2\/media\/49630"}],"wp:attachment":[{"href":"https:\/\/sentientmedia.org\/es\/wp-json\/wp\/v2\/media?parent=50152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sentientmedia.org\/es\/wp-json\/wp\/v2\/categories?post=50152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sentientmedia.org\/es\/wp-json\/wp\/v2\/tags?post=50152"},{"taxonomy":"sm-feature","embeddable":true,"href":"https:\/\/sentientmedia.org\/es\/wp-json\/wp\/v2\/sm-feature?post=50152"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/sentientmedia.org\/es\/wp-json\/wp\/v2\/coauthors?post=50152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}